{"id":25462,"date":"2024-12-05T18:10:12","date_gmt":"2024-12-05T18:10:12","guid":{"rendered":"https:\/\/iccomedical.ro\/?p=25462"},"modified":"2026-03-10T06:29:16","modified_gmt":"2026-03-10T06:29:16","slug":"top-radioprotection-with-m-by-mavig-now-in-romania","status":"publish","type":"post","link":"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/","title":{"rendered":"Top radiation protection with M by MAVIG, now in Romania"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"25462\" class=\"elementor elementor-25462\" data-elementor-post-type=\"post\">\n\t\t\t\t        <section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bd6cee elementor-section-boxed elementor-section-height-default elementor-section-height-default pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible\" data-id=\"6bd6cee\" data-element_type=\"section\">\n\n                \n                <div class=\"elementor-container elementor-column-gap-default \">\n                <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e0c3ebb pxl-column-none pxl-column-overflow-hidden-no\" data-id=\"e0c3ebb\" data-element_type=\"column\">\r\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\r\n                     \r\n        \t\t<div class=\"elementor-element elementor-element-5a98a78 typography-h3 text-dark  elementor-widget elementor-widget-pxl_heading\" data-id=\"5a98a78\" data-element_type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-5a98a78-5295\" class=\"pxl-heading px-sub-title-default-style \">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t<h3 class=\"pxl-item--title style-default  highlight-default \" data-wow-delay=\"ms\">\n\t\t\t\t\t\t\tCalitate german\u0103 la un cost eficient\t\n\t\t\t\t\n\t\t<\/h3>\n\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-160d54e typography-body1 text-mediumgray elementor-widget elementor-widget-pxl_text_editor\" data-id=\"160d54e\" data-element_type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner  \" data-wow-delay=\"ms\">\n\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 [&quot;table&quot;,{&quot;displayMode&quot;:null,&quot;isNumberColumnEnabled&quot;:false,&quot;layout&quot;:&quot;center&quot;,&quot;localId&quot;:&quot;e5c82278-2584-4ce4-a94c-bae204a1e4ce&quot;,&quot;width&quot;:1800,&quot;__autoSize&quot;:false},&quot;tableRow&quot;,null,&quot;tableCell&quot;,{&quot;colspan&quot;:1,&quot;rowspan&quot;:1,&quot;colwidth&quot;:[1142],&quot;background&quot;:null}]\"><strong>Produc\u0103torul MAVIG lanseaz\u0103 gama <a href=\"https:\/\/iccomedical.ro\/wp-content\/uploads\/2025\/08\/M-by-Mavig_CataloguePL_en_0225-1.pdf\">M by MAVIG<\/a><\/strong>, dedicat\u0103 profesioni\u0219tilor medicali. ICCO Medical aduce \u00een Rom\u00e2nia o colec\u021bie care p\u0103streaz\u0103 standardele ridicate, dar eficientizeaz\u0103 semnificativ pre\u021burile.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-154475b typography-h3 text-dark  elementor-widget elementor-widget-pxl_heading\" data-id=\"154475b\" data-element_type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-154475b-2567\" class=\"pxl-heading px-sub-title-default-style \">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t<h3 class=\"pxl-item--title style-default  highlight-default \" data-wow-delay=\"ms\">\n\t\t\t\t\t\t\tProtec\u021bie ridicat\u0103 \u0219i confort la purtare\t\n\t\t\t\t\n\t\t<\/h3>\n\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-edd1665 typography-body1 text-mediumgray elementor-widget elementor-widget-pxl_text_editor\" data-id=\"edd1665\" data-element_type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner  \" data-wow-delay=\"ms\">\n\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 [&quot;table&quot;,{&quot;displayMode&quot;:null,&quot;isNumberColumnEnabled&quot;:false,&quot;layout&quot;:&quot;center&quot;,&quot;localId&quot;:&quot;e5c82278-2584-4ce4-a94c-bae204a1e4ce&quot;,&quot;width&quot;:1800,&quot;__autoSize&quot;:false},&quot;tableRow&quot;,null,&quot;tableCell&quot;,{&quot;colspan&quot;:1,&quot;rowspan&quot;:1,&quot;colwidth&quot;:[1142],&quot;background&quot;:null}]\">Produsele sunt disponibile \u00een variante cu \u0219i f\u0103r\u0103 plumb (MPure\/MFree), oferind greutate redus\u0103 f\u0103r\u0103 a compromite protec\u021bia. Sunt certificate CE \u0219i rezistente la utilizare intens\u0103.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0e57a6 elementor-widget elementor-widget-pxl_image\" data-id=\"b0e57a6\" data-element_type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-b0e57a6-6215\" class=\"pxl-image-single df pxl-disable-parallax-sm pxl-hide-sr-lg  \" data-wow-delay=\"ms\"  >\r\n    <div class=\"pxl-item--inner\" data-wow-delay=\"120ms\">\r\n        \r\n                    <div class=\"pxl-item--image df\" data-parallax-value=\"\">\r\n                                <img fetchpriority=\"high\" decoding=\"async\" width=\"1978\" height=\"1884\" src=\"https:\/\/iccomedical.ro\/wp-content\/uploads\/2024\/12\/mavig-2.png\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                            <\/div>\r\n                \r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37c48af typography-h3 text-dark  elementor-widget elementor-widget-pxl_heading\" data-id=\"37c48af\" data-element_type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-37c48af-5559\" class=\"pxl-heading px-sub-title-default-style \">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t<h3 class=\"pxl-item--title style-default  highlight-default \" data-wow-delay=\"ms\">\n\t\t\t\t\t\t\tDesign modern \u0219i personalizare\t\n\t\t\t\t\n\t\t<\/h3>\n\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4f45d0 typography-body1 text-mediumgray elementor-widget elementor-widget-pxl_text_editor\" data-id=\"e4f45d0\" data-element_type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner  \" data-wow-delay=\"ms\">\n\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 [&quot;table&quot;,{&quot;displayMode&quot;:null,&quot;isNumberColumnEnabled&quot;:false,&quot;layout&quot;:&quot;center&quot;,&quot;localId&quot;:&quot;e5c82278-2584-4ce4-a94c-bae204a1e4ce&quot;,&quot;width&quot;:1800,&quot;__autoSize&quot;:false},&quot;tableRow&quot;,null,&quot;tableCell&quot;,{&quot;colspan&quot;:1,&quot;rowspan&quot;:1,&quot;colwidth&quot;:[1142],&quot;background&quot;:null}]\">Colec\u021bia include \u0219or\u021buri, protec\u021bii pentru g\u00e2t, cap \u0219i umeri. Se pot personaliza \u00een func\u021bie de preferin\u021be, iar \u00eentre\u021binerea este facil\u0103.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33cec59 typography-h3 text-dark  elementor-widget elementor-widget-pxl_heading\" data-id=\"33cec59\" data-element_type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-33cec59-9375\" class=\"pxl-heading px-sub-title-default-style \">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t<h3 class=\"pxl-item--title style-default  highlight-default \" data-wow-delay=\"ms\">\n\t\t\t\t\t\t\tO solu\u021bie complet\u0103 \u0219i sustenabil\u0103\t\n\t\t\t\t\n\t\t<\/h3>\n\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aecd05c typography-body1 text-mediumgray elementor-widget elementor-widget-pxl_text_editor\" data-id=\"aecd05c\" data-element_type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner  \" data-wow-delay=\"ms\">\n\t\t<p data-prosemirror-content-type=\"node\" data-prosemirror-node-name=\"paragraph\" data-prosemirror-node-block=\"true\" data-pm-slice=\"1 1 [&quot;table&quot;,{&quot;displayMode&quot;:null,&quot;isNumberColumnEnabled&quot;:false,&quot;layout&quot;:&quot;center&quot;,&quot;localId&quot;:&quot;e5c82278-2584-4ce4-a94c-bae204a1e4ce&quot;,&quot;width&quot;:1800,&quot;__autoSize&quot;:false},&quot;tableRow&quot;,null,&quot;tableCell&quot;,{&quot;colspan&quot;:1,&quot;rowspan&quot;:1,&quot;colwidth&quot;:[1142],&quot;background&quot;:null}]\">M by MAVIG r\u0103spunde nevoilor actuale ale pie\u021bei: siguran\u021b\u0103, confort \u0219i pre\u021b accesibil. ICCO Medical sprijin\u0103 spitalele cu echipamente durabile \u0219i eficiente.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1aa0f56 typography-h3 text-dark  elementor-widget elementor-widget-pxl_heading\" data-id=\"1aa0f56\" data-element_type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div id=\"pxl-pxl_heading-1aa0f56-1745\" class=\"pxl-heading px-sub-title-default-style \">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t<h3 class=\"pxl-item--title style-default  highlight-default \" data-wow-delay=\"ms\">\n\t\t\t\t\t\t\tTehnologie accesibil\u0103 pentru protec\u021bie de durat\u0103\t\n\t\t\t\t\n\t\t<\/h3>\n\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e7955d typography-body1 text-mediumgray elementor-widget elementor-widget-pxl_text_editor\" data-id=\"3e7955d\" data-element_type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-text-editor\">\n\t<div class=\"pxl-item--inner  \" data-wow-delay=\"ms\">\n\t\t<p>Noua colec\u021bie M by MAVIG este conceput\u0103 pentru a proteja eficient personalul medical, f\u0103r\u0103 a compromite confortul sau bugetul institu\u021biilor. Prin parteneriatul cu MAVIG, ICCO Medical ofer\u0103 o solu\u021bie sustenabil\u0103 \u0219i elegant\u0103 pentru centrele medicale care \u00ee\u0219i doresc cele mai bune standarde \u00een radioprotec\u021bie personal\u0103.<\/p>\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9bb51c elementor-widget elementor-widget-pxl_image\" data-id=\"c9bb51c\" data-element_type=\"widget\" data-widget_type=\"pxl_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_image-c9bb51c-7549\" class=\"pxl-image-single df pxl-disable-parallax-sm pxl-hide-sr-lg  \" data-wow-delay=\"ms\"  >\r\n    <div class=\"pxl-item--inner\" data-wow-delay=\"120ms\">\r\n        \r\n                    <div class=\"pxl-item--image df\" data-parallax-value=\"\">\r\n                                <img decoding=\"async\" width=\"1978\" height=\"894\" src=\"https:\/\/iccomedical.ro\/wp-content\/uploads\/2024\/12\/mavig-3.png\" class=\"no-lazyload attachment-full\" alt=\"\" \/>                                            <\/div>\r\n                \r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\r\n        <\/div>\r\n        \t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>MAVIG manufacturer launches the M by MAVIG range, dedicated to medical professionals. ICCO Medical brings to Romania a collection that maintains high standards while significantly streamlining prices.<\/p>","protected":false},"author":4,"featured_media":28159,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[151],"tags":[],"class_list":["post-25462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medical"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Radioprotec\u021bie de top cu M by MAVIG, acum \u00een Rom\u00e2nia - ICCO Medical - Echipamente medicale \u0219i speciale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iccomedical.ro\/en\/medical\/top-radioprotection-with-m-by-mavig-now-in-romania\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Radioprotec\u021bie de top cu M by MAVIG, acum \u00een Rom\u00e2nia - ICCO Medical - Echipamente medicale \u0219i speciale\" \/>\n<meta property=\"og:description\" content=\"Produc\u0103torul MAVIG lanseaz\u0103 gama M by MAVIG, dedicat\u0103 profesioni\u0219tilor medicali. ICCO Medical aduce \u00een Rom\u00e2nia o colec\u021bie care p\u0103streaz\u0103 standardele ridicate, dar eficientizeaz\u0103 semnificativ pre\u021burile.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iccomedical.ro\/en\/medical\/top-radioprotection-with-m-by-mavig-now-in-romania\/\" \/>\n<meta property=\"og:site_name\" content=\"ICCO Medical - Echipamente medicale \u0219i speciale\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-05T18:10:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-10T06:29:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iccomedical.ro\/wp-content\/uploads\/2024\/12\/Group-146@3x-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1464\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/\"},\"author\":{\"name\":\"Editor\",\"@id\":\"https:\/\/iccomedical.ro\/en\/#\/schema\/person\/164bc2959e2d02de2af7363efee95cf2\"},\"headline\":\"Radioprotec\u021bie de top cu M by MAVIG, acum \u00een Rom\u00e2nia\",\"datePublished\":\"2024-12-05T18:10:12+00:00\",\"dateModified\":\"2026-03-10T06:29:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/\"},\"wordCount\":203,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/iccomedical.ro\/en\/#organization\"},\"image\":{\"@id\":\"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/iccomedical.ro\/wp-content\/uploads\/2024\/12\/Group-146@3x-1.png\",\"articleSection\":[\"Medical\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/\",\"url\":\"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/\",\"name\":\"Radioprotec\u021bie de top cu M by MAVIG, acum \u00een Rom\u00e2nia - ICCO Medical - Echipamente medicale \u0219i speciale\",\"isPartOf\":{\"@id\":\"https:\/\/iccomedical.ro\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/iccomedical.ro\/wp-content\/uploads\/2024\/12\/Group-146@3x-1.png\",\"datePublished\":\"2024-12-05T18:10:12+00:00\",\"dateModified\":\"2026-03-10T06:29:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/#primaryimage\",\"url\":\"https:\/\/iccomedical.ro\/wp-content\/uploads\/2024\/12\/Group-146@3x-1.png\",\"contentUrl\":\"https:\/\/iccomedical.ro\/wp-content\/uploads\/2024\/12\/Group-146@3x-1.png\",\"width\":1464,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/iccomedical.ro\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Radioprotec\u021bie de top cu M by MAVIG, acum \u00een Rom\u00e2nia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/iccomedical.ro\/en\/#website\",\"url\":\"https:\/\/iccomedical.ro\/en\/\",\"name\":\"ICCO Medical - Echipamente medicale \u0219i speciale\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/iccomedical.ro\/en\/#organization\"},\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/iccomedical.ro\/en\/#organization\",\"name\":\"ICCO Medical - Echipamente medicale \u0219i speciale\",\"url\":\"https:\/\/iccomedical.ro\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/iccomedical.ro\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/iccomedical.ro\/wp-content\/uploads\/2025\/02\/cropped-icco-512-light.png\",\"contentUrl\":\"https:\/\/iccomedical.ro\/wp-content\/uploads\/2025\/02\/cropped-icco-512-light.png\",\"width\":512,\"height\":512,\"caption\":\"ICCO Medical - Echipamente medicale \u0219i speciale\"},\"image\":{\"@id\":\"https:\/\/iccomedical.ro\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/iccomedical.ro\/en\/#\/schema\/person\/164bc2959e2d02de2af7363efee95cf2\",\"name\":\"Editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/iccomedical.ro\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/iccomedical.ro\/wp-content\/litespeed\/avatar\/07768c9157d7237c3f06dd6c377b86ee.jpg?ver=1783687380\",\"contentUrl\":\"https:\/\/iccomedical.ro\/wp-content\/litespeed\/avatar\/07768c9157d7237c3f06dd6c377b86ee.jpg?ver=1783687380\",\"caption\":\"Editor\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Top radioprotection with M by MAVIG, now in Romania - ICCO Medical - Medical and special equipment","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iccomedical.ro\/en\/medical\/top-radioprotection-with-m-by-mavig-now-in-romania\/","og_locale":"en_US","og_type":"article","og_title":"Radioprotec\u021bie de top cu M by MAVIG, acum \u00een Rom\u00e2nia - ICCO Medical - Echipamente medicale \u0219i speciale","og_description":"Produc\u0103torul MAVIG lanseaz\u0103 gama M by MAVIG, dedicat\u0103 profesioni\u0219tilor medicali. ICCO Medical aduce \u00een Rom\u00e2nia o colec\u021bie care p\u0103streaz\u0103 standardele ridicate, dar eficientizeaz\u0103 semnificativ pre\u021burile.","og_url":"https:\/\/iccomedical.ro\/en\/medical\/top-radioprotection-with-m-by-mavig-now-in-romania\/","og_site_name":"ICCO Medical - Echipamente medicale \u0219i speciale","article_published_time":"2024-12-05T18:10:12+00:00","article_modified_time":"2026-03-10T06:29:16+00:00","og_image":[{"width":1464,"height":1500,"url":"https:\/\/iccomedical.ro\/wp-content\/uploads\/2024\/12\/Group-146@3x-1.png","type":"image\/png"}],"author":"Editor","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Editor","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/#article","isPartOf":{"@id":"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/"},"author":{"name":"Editor","@id":"https:\/\/iccomedical.ro\/en\/#\/schema\/person\/164bc2959e2d02de2af7363efee95cf2"},"headline":"Radioprotec\u021bie de top cu M by MAVIG, acum \u00een Rom\u00e2nia","datePublished":"2024-12-05T18:10:12+00:00","dateModified":"2026-03-10T06:29:16+00:00","mainEntityOfPage":{"@id":"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/"},"wordCount":203,"commentCount":0,"publisher":{"@id":"https:\/\/iccomedical.ro\/en\/#organization"},"image":{"@id":"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/#primaryimage"},"thumbnailUrl":"https:\/\/iccomedical.ro\/wp-content\/uploads\/2024\/12\/Group-146@3x-1.png","articleSection":["Medical"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/","url":"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/","name":"Top radioprotection with M by MAVIG, now in Romania - ICCO Medical - Medical and special equipment","isPartOf":{"@id":"https:\/\/iccomedical.ro\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/#primaryimage"},"image":{"@id":"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/#primaryimage"},"thumbnailUrl":"https:\/\/iccomedical.ro\/wp-content\/uploads\/2024\/12\/Group-146@3x-1.png","datePublished":"2024-12-05T18:10:12+00:00","dateModified":"2026-03-10T06:29:16+00:00","breadcrumb":{"@id":"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/#primaryimage","url":"https:\/\/iccomedical.ro\/wp-content\/uploads\/2024\/12\/Group-146@3x-1.png","contentUrl":"https:\/\/iccomedical.ro\/wp-content\/uploads\/2024\/12\/Group-146@3x-1.png","width":1464,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/iccomedical.ro\/en\/medical\/radioprotectie-de-top-cu-m-by-mavig-acum-in-romania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/iccomedical.ro\/"},{"@type":"ListItem","position":2,"name":"Radioprotec\u021bie de top cu M by MAVIG, acum \u00een Rom\u00e2nia"}]},{"@type":"WebSite","@id":"https:\/\/iccomedical.ro\/en\/#website","url":"https:\/\/iccomedical.ro\/en\/","name":"ICCO Medical - Medical and special equipment","description":"","publisher":{"@id":"https:\/\/iccomedical.ro\/en\/#organization"},"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/iccomedical.ro\/en\/#organization","name":"ICCO Medical - Medical and special equipment","url":"https:\/\/iccomedical.ro\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/iccomedical.ro\/en\/#\/schema\/logo\/image\/","url":"https:\/\/iccomedical.ro\/wp-content\/uploads\/2025\/02\/cropped-icco-512-light.png","contentUrl":"https:\/\/iccomedical.ro\/wp-content\/uploads\/2025\/02\/cropped-icco-512-light.png","width":512,"height":512,"caption":"ICCO Medical - Echipamente medicale \u0219i speciale"},"image":{"@id":"https:\/\/iccomedical.ro\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/iccomedical.ro\/en\/#\/schema\/person\/164bc2959e2d02de2af7363efee95cf2","name":"Editor","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/iccomedical.ro\/en\/#\/schema\/person\/image\/","url":"https:\/\/iccomedical.ro\/wp-content\/litespeed\/avatar\/07768c9157d7237c3f06dd6c377b86ee.jpg?ver=1783687380","contentUrl":"https:\/\/iccomedical.ro\/wp-content\/litespeed\/avatar\/07768c9157d7237c3f06dd6c377b86ee.jpg?ver=1783687380","caption":"Editor"}}]}},"_links":{"self":[{"href":"https:\/\/iccomedical.ro\/en\/wp-json\/wp\/v2\/posts\/25462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iccomedical.ro\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iccomedical.ro\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iccomedical.ro\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/iccomedical.ro\/en\/wp-json\/wp\/v2\/comments?post=25462"}],"version-history":[{"count":0,"href":"https:\/\/iccomedical.ro\/en\/wp-json\/wp\/v2\/posts\/25462\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iccomedical.ro\/en\/wp-json\/wp\/v2\/media\/28159"}],"wp:attachment":[{"href":"https:\/\/iccomedical.ro\/en\/wp-json\/wp\/v2\/media?parent=25462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iccomedical.ro\/en\/wp-json\/wp\/v2\/categories?post=25462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iccomedical.ro\/en\/wp-json\/wp\/v2\/tags?post=25462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}